{"id":4981,"date":"2022-11-20T14:44:35","date_gmt":"2022-11-20T11:44:35","guid":{"rendered":"https:\/\/wanasahdesign.com\/product\/%d8%b3%d8%aa%d9%8a%d9%83%d8%b1%d8%b2-%d8%b4%d9%83%d9%84-%d8%b1%d9%8a%d8%b4-%d8%a8%d8%a7%d9%84%d9%84%d9%88%d9%86-%d8%a7%d9%84%d8%a8%d9%86%d9%81%d8%b3%d8%ac%d9%8a-%d9%88%d8%a7%d9%84%d8%b1%d9%85%d8%a7\/"},"modified":"2022-11-20T14:44:35","modified_gmt":"2022-11-20T11:44:35","slug":"%d8%b3%d8%aa%d9%8a%d9%83%d8%b1%d8%b2-%d8%b4%d9%83%d9%84-%d8%b1%d9%8a%d8%b4-%d8%a8%d8%a7%d9%84%d9%84%d9%88%d9%86-%d8%a7%d9%84%d8%a8%d9%86%d9%81%d8%b3%d8%ac%d9%8a-%d9%88%d8%a7%d9%84%d8%b1%d9%85%d8%a7","status":"publish","type":"product","link":"https:\/\/wanasahdesign.com\/ar\/product\/%d8%b3%d8%aa%d9%8a%d9%83%d8%b1%d8%b2-%d8%b4%d9%83%d9%84-%d8%b1%d9%8a%d8%b4-%d8%a8%d8%a7%d9%84%d9%84%d9%88%d9%86-%d8%a7%d9%84%d8%a8%d9%86%d9%81%d8%b3%d8%ac%d9%8a-%d9%88%d8%a7%d9%84%d8%b1%d9%85%d8%a7\/","title":{"rendered":"\u0633\u062a\u064a\u0643\u0631\u0632 \u0634\u0643\u0644 \u0631\u064a\u0634 \u0628\u0627\u0644\u0644\u0648\u0646 \u0627\u0644\u0628\u0646\u0641\u0633\u062c\u064a \u0648\u0627\u0644\u0631\u0645\u0627\u062f\u064a"},"content":{"rendered":"<p>\u2013 \u0633\u062a\u064a\u0643\u0631\u0632 \u0645\u0637\u0628\u0648\u0639 \u0628\u0623\u062d\u0628\u0627\u0631 \u0644\u0627\u062a\u0643\u0633 \u0627\u062a\u0634 \u0628\u064a. \u0635\u062f\u064a\u0642\u0629 \u0644\u0644\u0628\u064a\u0626\u0629<br \/>\n\u2013 \u064a\u0648\u062c\u062f \u0628\u0627\u0644\u0627\u0633\u062a\u064a\u0643\u0631 \u0637\u0628\u0642\u0629 \u0644\u0635\u0642 \u0630\u0627\u062a\u064a\u0629 \u0645\u0646 \u0627\u0644\u062e\u0644\u0641<br \/>\n\u2013 \u064a\u0645\u0643\u0646 \u0644\u0635\u0642 \u0627\u0644\u0627\u0633\u062a\u064a\u0643\u0631 \u0639\u0644\u064a \u0623\u064a \u0633\u0637\u062d \u0646\u0627\u0639\u0645 ( \u062d\u0648\u0627\u0626\u0637 \u060c \u0632\u062c\u0627\u062c \u060c \u062e\u0634\u0628 )<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2013 \u0633\u062a\u064a\u0643\u0631\u0632 \u0645\u0637\u0628\u0648\u0639 \u0628\u0642\u064a\u0627\u0633\u0627\u062a \u0645\u062a\u0639\u062f\u062f\u0629<br \/>\n\u2013 \u0644\u0637\u0644\u0628 \u0627\u0644\u0627\u0633\u062a\u064a\u0643\u0631\u0632 \u0628\u0642\u064a\u0627\u0633\u0627\u062a \u062e\u0627\u0635\u0629 \u064a\u0631\u062c\u0649 \u0627\u0644\u062a\u0648\u0627\u0635\u0644 \u0645\u0639 \u062e\u062f\u0645\u0629 \u0639\u0645\u0644\u0627\u0621<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":4980,"template":"","meta":[],"product_brand":[],"product_cat":[272],"product_tag":[],"class_list":{"0":"post-4981","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-wall-stickers-ar","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-variable"},"ams_default_variation_id":0,"ams_product_points_reward":[],"ams_product_discount_percentage":0,"ams_price_to_display":48,"ams_acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0633\u062a\u064a\u0643\u0631\u0632 \u0634\u0643\u0644 \u0631\u064a\u0634 \u0628\u0627\u0644\u0644\u0648\u0646 \u0627\u0644\u0628\u0646\u0641\u0633\u062c\u064a \u0648\u0627\u0644\u0631\u0645\u0627\u062f\u064a - Wanasah Design (paintings, stickers, curtains, home decor)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wanasahdesign.com\/product\/purple-and-gray-feather-sticker\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0633\u062a\u064a\u0643\u0631\u0632 \u0634\u0643\u0644 \u0631\u064a\u0634 \u0628\u0627\u0644\u0644\u0648\u0646 \u0627\u0644\u0628\u0646\u0641\u0633\u062c\u064a \u0648\u0627\u0644\u0631\u0645\u0627\u062f\u064a - Wanasah Design (paintings, stickers, curtains, home decor)\" \/>\n<meta property=\"og:description\" content=\"\u2013 \u0633\u062a\u064a\u0643\u0631\u0632 \u0645\u0637\u0628\u0648\u0639 \u0628\u0642\u064a\u0627\u0633\u0627\u062a \u0645\u062a\u0639\u062f\u062f\u0629 \u2013 \u0644\u0637\u0644\u0628 \u0627\u0644\u0627\u0633\u062a\u064a\u0643\u0631\u0632 \u0628\u0642\u064a\u0627\u0633\u0627\u062a \u062e\u0627\u0635\u0629 \u064a\u0631\u062c\u0649 \u0627\u0644\u062a\u0648\u0627\u0635\u0644 \u0645\u0639 \u062e\u062f\u0645\u0629 \u0639\u0645\u0644\u0627\u0621  &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wanasahdesign.com\/product\/purple-and-gray-feather-sticker\/\" \/>\n<meta property=\"og:site_name\" content=\"Wanasah Design (paintings, stickers, curtains, home decor)\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WanasahDesign\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wanasahdesign.com\/wp-content\/uploads\/2022\/11\/WS11512.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wanasahdesign.com\\\/product\\\/purple-and-gray-feather-sticker\\\/\",\"url\":\"https:\\\/\\\/wanasahdesign.com\\\/product\\\/purple-and-gray-feather-sticker\\\/\",\"name\":\"\u0633\u062a\u064a\u0643\u0631\u0632 \u0634\u0643\u0644 \u0631\u064a\u0634 \u0628\u0627\u0644\u0644\u0648\u0646 \u0627\u0644\u0628\u0646\u0641\u0633\u062c\u064a \u0648\u0627\u0644\u0631\u0645\u0627\u062f\u064a - Wanasah Design (paintings, stickers, curtains, home decor)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wanasahdesign.com\\\/ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wanasahdesign.com\\\/product\\\/purple-and-gray-feather-sticker\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wanasahdesign.com\\\/product\\\/purple-and-gray-feather-sticker\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/wanasahdesign.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/WS11512.jpg?fit=800%2C800&ssl=1\",\"datePublished\":\"2022-11-20T11:44:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wanasahdesign.com\\\/product\\\/purple-and-gray-feather-sticker\\\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wanasahdesign.com\\\/product\\\/purple-and-gray-feather-sticker\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/wanasahdesign.com\\\/product\\\/purple-and-gray-feather-sticker\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/wanasahdesign.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/WS11512.jpg?fit=800%2C800&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/wanasahdesign.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/WS11512.jpg?fit=800%2C800&ssl=1\",\"width\":800,\"height\":800,\"caption\":\"\u0633\u062a\u064a\u0643\u0631\u0632 \u0634\u0643\u0644 \u0631\u064a\u0634 \u0628\u0627\u0644\u0644\u0648\u0646 \u0627\u0644\u0628\u0646\u0641\u0633\u062c\u064a \u0648\u0627\u0644\u0631\u0645\u0627\u062f\u064a\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wanasahdesign.com\\\/product\\\/purple-and-gray-feather-sticker\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wanasahdesign.com\\\/ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0627\u0644\u0633\u0648\u0642\",\"item\":\"https:\\\/\\\/wanasahdesign.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0633\u062a\u064a\u0643\u0631\u0632 \u0634\u0643\u0644 \u0631\u064a\u0634 \u0628\u0627\u0644\u0644\u0648\u0646 \u0627\u0644\u0628\u0646\u0641\u0633\u062c\u064a \u0648\u0627\u0644\u0631\u0645\u0627\u062f\u064a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wanasahdesign.com\\\/ar\\\/#website\",\"url\":\"https:\\\/\\\/wanasahdesign.com\\\/ar\\\/\",\"name\":\"Wanasah Design (paintings, stickers, curtains, home decor)\",\"description\":\"\u0648\u0646\u0627\u0633\u0647 \u062f\u064a\u0632\u0627\u064a\u0646 ( \u0644\u0648\u062d\u0627\u062a \u060c \u0633\u062a\u064a\u0643\u0631\u0632 \u060c \u0633\u062a\u0627\u0626\u0631 \u060c \u062f\u064a\u0643\u0648\u0631 \u0645\u0646\u0632\u0644\u064a )\",\"publisher\":{\"@id\":\"https:\\\/\\\/wanasahdesign.com\\\/ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wanasahdesign.com\\\/ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wanasahdesign.com\\\/ar\\\/#organization\",\"name\":\"Wanasah Design\",\"url\":\"https:\\\/\\\/wanasahdesign.com\\\/ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/wanasahdesign.com\\\/ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/wanasahdesign.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/WebSite-Logo05555551.png?fit=480%2C170&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/wanasahdesign.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/WebSite-Logo05555551.png?fit=480%2C170&ssl=1\",\"width\":480,\"height\":170,\"caption\":\"Wanasah Design\"},\"image\":{\"@id\":\"https:\\\/\\\/wanasahdesign.com\\\/ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WanasahDesign\\\/\",\"https:\\\/\\\/www.instagram.com\\\/wanasahdesign_kw\\\/\",\"https:\\\/\\\/youtube.com\\\/channel\\\/UCsguHmI9DJwhXXxEKvNZ4yQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0633\u062a\u064a\u0643\u0631\u0632 \u0634\u0643\u0644 \u0631\u064a\u0634 \u0628\u0627\u0644\u0644\u0648\u0646 \u0627\u0644\u0628\u0646\u0641\u0633\u062c\u064a \u0648\u0627\u0644\u0631\u0645\u0627\u062f\u064a - Wanasah Design (paintings, stickers, curtains, home decor)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wanasahdesign.com\/product\/purple-and-gray-feather-sticker\/","og_locale":"ar_AR","og_type":"article","og_title":"\u0633\u062a\u064a\u0643\u0631\u0632 \u0634\u0643\u0644 \u0631\u064a\u0634 \u0628\u0627\u0644\u0644\u0648\u0646 \u0627\u0644\u0628\u0646\u0641\u0633\u062c\u064a \u0648\u0627\u0644\u0631\u0645\u0627\u062f\u064a - Wanasah Design (paintings, stickers, curtains, home decor)","og_description":"\u2013 \u0633\u062a\u064a\u0643\u0631\u0632 \u0645\u0637\u0628\u0648\u0639 \u0628\u0642\u064a\u0627\u0633\u0627\u062a \u0645\u062a\u0639\u062f\u062f\u0629 \u2013 \u0644\u0637\u0644\u0628 \u0627\u0644\u0627\u0633\u062a\u064a\u0643\u0631\u0632 \u0628\u0642\u064a\u0627\u0633\u0627\u062a \u062e\u0627\u0635\u0629 \u064a\u0631\u062c\u0649 \u0627\u0644\u062a\u0648\u0627\u0635\u0644 \u0645\u0639 \u062e\u062f\u0645\u0629 \u0639\u0645\u0644\u0627\u0621  &nbsp;","og_url":"https:\/\/wanasahdesign.com\/product\/purple-and-gray-feather-sticker\/","og_site_name":"Wanasah Design (paintings, stickers, curtains, home decor)","article_publisher":"https:\/\/www.facebook.com\/WanasahDesign\/","og_image":[{"width":800,"height":800,"url":"https:\/\/wanasahdesign.com\/wp-content\/uploads\/2022\/11\/WS11512.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wanasahdesign.com\/product\/purple-and-gray-feather-sticker\/","url":"https:\/\/wanasahdesign.com\/product\/purple-and-gray-feather-sticker\/","name":"\u0633\u062a\u064a\u0643\u0631\u0632 \u0634\u0643\u0644 \u0631\u064a\u0634 \u0628\u0627\u0644\u0644\u0648\u0646 \u0627\u0644\u0628\u0646\u0641\u0633\u062c\u064a \u0648\u0627\u0644\u0631\u0645\u0627\u062f\u064a - Wanasah Design (paintings, stickers, curtains, home decor)","isPartOf":{"@id":"https:\/\/wanasahdesign.com\/ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wanasahdesign.com\/product\/purple-and-gray-feather-sticker\/#primaryimage"},"image":{"@id":"https:\/\/wanasahdesign.com\/product\/purple-and-gray-feather-sticker\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/wanasahdesign.com\/wp-content\/uploads\/2022\/11\/WS11512.jpg?fit=800%2C800&ssl=1","datePublished":"2022-11-20T11:44:35+00:00","breadcrumb":{"@id":"https:\/\/wanasahdesign.com\/product\/purple-and-gray-feather-sticker\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wanasahdesign.com\/product\/purple-and-gray-feather-sticker\/"]}]},{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/wanasahdesign.com\/product\/purple-and-gray-feather-sticker\/#primaryimage","url":"https:\/\/i0.wp.com\/wanasahdesign.com\/wp-content\/uploads\/2022\/11\/WS11512.jpg?fit=800%2C800&ssl=1","contentUrl":"https:\/\/i0.wp.com\/wanasahdesign.com\/wp-content\/uploads\/2022\/11\/WS11512.jpg?fit=800%2C800&ssl=1","width":800,"height":800,"caption":"\u0633\u062a\u064a\u0643\u0631\u0632 \u0634\u0643\u0644 \u0631\u064a\u0634 \u0628\u0627\u0644\u0644\u0648\u0646 \u0627\u0644\u0628\u0646\u0641\u0633\u062c\u064a \u0648\u0627\u0644\u0631\u0645\u0627\u062f\u064a"},{"@type":"BreadcrumbList","@id":"https:\/\/wanasahdesign.com\/product\/purple-and-gray-feather-sticker\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wanasahdesign.com\/ar\/"},{"@type":"ListItem","position":2,"name":"\u0627\u0644\u0633\u0648\u0642","item":"https:\/\/wanasahdesign.com\/shop\/"},{"@type":"ListItem","position":3,"name":"\u0633\u062a\u064a\u0643\u0631\u0632 \u0634\u0643\u0644 \u0631\u064a\u0634 \u0628\u0627\u0644\u0644\u0648\u0646 \u0627\u0644\u0628\u0646\u0641\u0633\u062c\u064a \u0648\u0627\u0644\u0631\u0645\u0627\u062f\u064a"}]},{"@type":"WebSite","@id":"https:\/\/wanasahdesign.com\/ar\/#website","url":"https:\/\/wanasahdesign.com\/ar\/","name":"Wanasah Design (paintings, stickers, curtains, home decor)","description":"\u0648\u0646\u0627\u0633\u0647 \u062f\u064a\u0632\u0627\u064a\u0646 ( \u0644\u0648\u062d\u0627\u062a \u060c \u0633\u062a\u064a\u0643\u0631\u0632 \u060c \u0633\u062a\u0627\u0626\u0631 \u060c \u062f\u064a\u0643\u0648\u0631 \u0645\u0646\u0632\u0644\u064a )","publisher":{"@id":"https:\/\/wanasahdesign.com\/ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wanasahdesign.com\/ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/wanasahdesign.com\/ar\/#organization","name":"Wanasah Design","url":"https:\/\/wanasahdesign.com\/ar\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/wanasahdesign.com\/ar\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/wanasahdesign.com\/wp-content\/uploads\/2023\/07\/WebSite-Logo05555551.png?fit=480%2C170&ssl=1","contentUrl":"https:\/\/i0.wp.com\/wanasahdesign.com\/wp-content\/uploads\/2023\/07\/WebSite-Logo05555551.png?fit=480%2C170&ssl=1","width":480,"height":170,"caption":"Wanasah Design"},"image":{"@id":"https:\/\/wanasahdesign.com\/ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WanasahDesign\/","https:\/\/www.instagram.com\/wanasahdesign_kw\/","https:\/\/youtube.com\/channel\/UCsguHmI9DJwhXXxEKvNZ4yQ"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/wanasahdesign.com\/ar\/wp-json\/wp\/v2\/product\/4981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wanasahdesign.com\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/wanasahdesign.com\/ar\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wanasahdesign.com\/ar\/wp-json\/wp\/v2\/media\/4980"}],"wp:attachment":[{"href":"https:\/\/wanasahdesign.com\/ar\/wp-json\/wp\/v2\/media?parent=4981"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/wanasahdesign.com\/ar\/wp-json\/wp\/v2\/product_brand?post=4981"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/wanasahdesign.com\/ar\/wp-json\/wp\/v2\/product_cat?post=4981"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/wanasahdesign.com\/ar\/wp-json\/wp\/v2\/product_tag?post=4981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}